{"id":367,"date":"2020-05-11T16:28:18","date_gmt":"2020-05-11T16:28:18","guid":{"rendered":"http:\/\/roycypher.com\/activity\/"},"modified":"2020-05-11T16:28:18","modified_gmt":"2020-05-11T16:28:18","slug":"activity","status":"publish","type":"page","link":"http:\/\/city-refuge.org\/roycypher\/activity\/","title":{"rendered":"Activity"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"class_list":["post-367","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/pages\/367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/comments?post=367"}],"version-history":[{"count":0,"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/pages\/367\/revisions"}],"wp:attachment":[{"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/media?parent=367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}