{"id":698,"date":"2022-12-29T10:43:02","date_gmt":"2022-12-29T10:43:02","guid":{"rendered":"http:\/\/city-refuge.org\/roycypher\/?p=698"},"modified":"2022-12-29T10:43:02","modified_gmt":"2022-12-29T10:43:02","slug":"restoration-love-center-12-25-22","status":"publish","type":"post","link":"http:\/\/city-refuge.org\/roycypher\/2022\/12\/29\/restoration-love-center-12-25-22\/","title":{"rendered":"Restoration Love Center 12\/25\/22"},"content":{"rendered":"<figure class=\"wp-block-embed wp-block-embed-youtube is-type-video is-provider-youtube epyt-figure\"><div class=\"wp-block-embed__wrapper\"><iframe loading=\"lazy\"  id=\"_ytid_58473\"  width=\"480\" height=\"270\"  data-origwidth=\"480\" data-origheight=\"270\" src=\"https:\/\/www.youtube.com\/embed\/q3YfMeAIpAk?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=1&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&\" class=\"__youtube_prefs__  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[2],"tags":[],"series":[],"class_list":["post-698","post","type-post","status-publish","format-standard","hentry","category-roy-cypher","wpcat-2-id"],"episode_featured_image":false,"episode_player_image":"http:\/\/city-refuge.org\/roycypher\/wp-content\/plugins\/seriously-simple-podcasting\/assets\/images\/no-album-art.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"http:\/\/city-refuge.org\/roycypher\/feed\/podcast\/roy-cypher","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"oAhIKUPzlo\"><a href=\"http:\/\/city-refuge.org\/roycypher\/2022\/12\/29\/restoration-love-center-12-25-22\/\">Restoration Love Center 12\/25\/22<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"http:\/\/city-refuge.org\/roycypher\/2022\/12\/29\/restoration-love-center-12-25-22\/embed\/#?secret=oAhIKUPzlo\" width=\"500\" height=\"350\" title=\"&#8220;Restoration Love Center 12\/25\/22&#8221; &#8212; Roy Cypher\" data-secret=\"oAhIKUPzlo\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/posts\/698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/comments?post=698"}],"version-history":[{"count":1,"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/posts\/698\/revisions"}],"predecessor-version":[{"id":699,"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/posts\/698\/revisions\/699"}],"wp:attachment":[{"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/media?parent=698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/categories?post=698"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/tags?post=698"},{"taxonomy":"series","embeddable":true,"href":"http:\/\/city-refuge.org\/roycypher\/wp-json\/wp\/v2\/series?post=698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}