{"id":321,"date":"2024-06-28T23:24:16","date_gmt":"2024-06-28T23:24:16","guid":{"rendered":"http:\/\/city-refuge.org\/street\/2024\/06\/28\/house-church-conference-2024\/"},"modified":"2024-06-28T23:25:41","modified_gmt":"2024-06-28T23:25:41","slug":"house-church-conference-2024","status":"publish","type":"post","link":"http:\/\/city-refuge.org\/street\/2024\/06\/28\/house-church-conference-2024\/","title":{"rendered":"House Church Conference 2024"},"content":{"rendered":"<div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  style=\"display: block; margin: 0px auto;\"  id=\"_ytid_21751\"  width=\"640\" height=\"360\"  data-origwidth=\"640\" data-origheight=\"360\"  data-relstop=\"1\" src=\"https:\/\/www.youtube.com\/embed\/UYp7J8_ykZA?enablejsapi=1&autoplay=1&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=0&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&\" class=\"__youtube_prefs__  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-321","post","type-post","status-publish","format-standard","hentry","category-house-chruch"],"_links":{"self":[{"href":"http:\/\/city-refuge.org\/street\/wp-json\/wp\/v2\/posts\/321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/city-refuge.org\/street\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/city-refuge.org\/street\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/city-refuge.org\/street\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/city-refuge.org\/street\/wp-json\/wp\/v2\/comments?post=321"}],"version-history":[{"count":1,"href":"http:\/\/city-refuge.org\/street\/wp-json\/wp\/v2\/posts\/321\/revisions"}],"predecessor-version":[{"id":322,"href":"http:\/\/city-refuge.org\/street\/wp-json\/wp\/v2\/posts\/321\/revisions\/322"}],"wp:attachment":[{"href":"http:\/\/city-refuge.org\/street\/wp-json\/wp\/v2\/media?parent=321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/city-refuge.org\/street\/wp-json\/wp\/v2\/categories?post=321"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/city-refuge.org\/street\/wp-json\/wp\/v2\/tags?post=321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}